{"id":3722,"date":"2018-04-10T19:56:47","date_gmt":"2018-04-10T19:56:47","guid":{"rendered":"https:\/\/zdvo.org\/unkategorisiert\/a-second-home-beit-halochem-centers\/"},"modified":"2018-10-04T15:12:19","modified_gmt":"2018-10-04T15:12:19","slug":"a-second-home-beit-halochem-centers","status":"publish","type":"post","link":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/","title":{"rendered":"Ein &#8222;Zweites Zuhause&#8220; \u2013 Beit Halochem-Zentren"},"content":{"rendered":"<p><strong class=\"article-sammury\">Beit Halochem ist ein einzigartiges Rehabilitation-, Sport- und Freizeitzentrum f\u00fcr kriegsbesch\u00e4digte Veteranen und ihre Familien. Es bietet einen Ort, an dem die Kriegsbesch\u00e4digten die verschiedenen Behandlungen erhalten, die sie bis an ihr Lebensende ben\u00f6tigen. Der Schwerpunkt liegt dabei auf Sport als Rehabilitationsmittel, gemeinsam mit einer breiten Vielfalt an sozialen und kulturellen Programmen.<\/strong><\/p>\n<p>Beit Halochem vertritt die Philosophie, dass die Kriegsbesch\u00e4digten in einem Umfeld umsorgt werden sollen, das sowohl f\u00fcr sie als auch f\u00fcr die sie umgebenden Personen angenehm ist. Im Einklang mit dieser Philosophie bietet es eine Vielfalt von Aktivit\u00e4ten, um die Familie, sowohl Erwachsene als auch Kinder, zu besch\u00e4ftigen.<\/p>\n<p>Ein wichtiges Merkmal des Beit Halochem ist die Begegnung zwischen Generationen, wobei Erfahrene mit Neuank\u00f6mmlingen zusammengebracht werden, die lernen m\u00fcssen, sich an die schwere und komplizierte Welt der Behinderung anzupassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beit Halochem ist ein einzigartiges Rehabilitation-, Sport- und Freizeitzentrum f\u00fcr kriegsbesch\u00e4digte Veteranen und ihre Familien. Es bietet einen Ort, an dem die Kriegsbesch\u00e4digten die verschiedenen Behandlungen erhalten, die sie bis [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":3723,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[84,85],"tags":[],"class_list":["post-3722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-about-de","category-bet-halochem-centers-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein &quot;Zweites Zuhause&quot; \u2013 Beit Halochem-Zentren - zdvo.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein &quot;Zweites Zuhause&quot; \u2013 Beit Halochem-Zentren - zdvo.org\" \/>\n<meta property=\"og:description\" content=\"Beit Halochem ist ein einzigartiges Rehabilitation-, Sport- und Freizeitzentrum f\u00fcr kriegsbesch\u00e4digte Veteranen und ihre Familien. Es bietet einen Ort, an dem die Kriegsbesch\u00e4digten die verschiedenen Behandlungen erhalten, die sie bis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/\" \/>\n<meta property=\"og:site_name\" content=\"zdvo.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zdvo.halochem\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-10T19:56:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-04T15:12:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zdvo.org\/wp-content\/uploads\/2018\/04\/513.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#\\\/schema\\\/person\\\/2ed98dea9ff2fe660f1caf1174f49fcf\"},\"headline\":\"Ein &#8222;Zweites Zuhause&#8220; \u2013 Beit Halochem-Zentren\",\"datePublished\":\"2018-04-10T19:56:47+00:00\",\"dateModified\":\"2018-10-04T15:12:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/\"},\"wordCount\":146,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zdvo.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/513.jpg\",\"articleSection\":[\"About\",\"BEIT HALOCHEM-ZENTREN\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/\",\"url\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/\",\"name\":\"Ein \\\"Zweites Zuhause\\\" \u2013 Beit Halochem-Zentren - zdvo.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zdvo.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/513.jpg\",\"datePublished\":\"2018-04-10T19:56:47+00:00\",\"dateModified\":\"2018-10-04T15:12:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zdvo.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/513.jpg\",\"contentUrl\":\"https:\\\/\\\/zdvo.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/513.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/a-second-home-beit-halochem-centers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zdvo.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein &#8222;Zweites Zuhause&#8220; \u2013 Beit Halochem-Zentren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/zdvo.org\\\/de\\\/\",\"name\":\"zdvo.org\",\"description\":\"The Zahal Disabled Veterans Organization (ZDVO) is a registered non-profit organization with the purpose of providing disabled veterans all their needs towards their rehabilitation.\",\"publisher\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zdvo.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#organization\",\"name\":\"zdvo\",\"url\":\"https:\\\/\\\/zdvo.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zdvo.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/KEREN_IDF_Veterans_ENGLISH_Beit_ha_lochem_Logo_CMYK_Blue.png\",\"contentUrl\":\"https:\\\/\\\/zdvo.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/KEREN_IDF_Veterans_ENGLISH_Beit_ha_lochem_Logo_CMYK_Blue.png\",\"width\":1566,\"height\":382,\"caption\":\"zdvo\"},\"image\":{\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zdvo.halochem\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zdvo.org\\\/de\\\/#\\\/schema\\\/person\\\/2ed98dea9ff2fe660f1caf1174f49fcf\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/297c0af693852fda6a0b04cc7e57c482a131fcde794e6c4cc3be61fc94a42b7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/297c0af693852fda6a0b04cc7e57c482a131fcde794e6c4cc3be61fc94a42b7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/297c0af693852fda6a0b04cc7e57c482a131fcde794e6c4cc3be61fc94a42b7c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/zdvo.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein \"Zweites Zuhause\" \u2013 Beit Halochem-Zentren - zdvo.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/","og_locale":"de_DE","og_type":"article","og_title":"Ein \"Zweites Zuhause\" \u2013 Beit Halochem-Zentren - zdvo.org","og_description":"Beit Halochem ist ein einzigartiges Rehabilitation-, Sport- und Freizeitzentrum f\u00fcr kriegsbesch\u00e4digte Veteranen und ihre Familien. Es bietet einen Ort, an dem die Kriegsbesch\u00e4digten die verschiedenen Behandlungen erhalten, die sie bis [&hellip;]","og_url":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/","og_site_name":"zdvo.org","article_publisher":"https:\/\/www.facebook.com\/zdvo.halochem\/","article_published_time":"2018-04-10T19:56:47+00:00","article_modified_time":"2018-10-04T15:12:19+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/zdvo.org\/wp-content\/uploads\/2018\/04\/513.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#article","isPartOf":{"@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/"},"author":{"name":"admin","@id":"https:\/\/zdvo.org\/de\/#\/schema\/person\/2ed98dea9ff2fe660f1caf1174f49fcf"},"headline":"Ein &#8222;Zweites Zuhause&#8220; \u2013 Beit Halochem-Zentren","datePublished":"2018-04-10T19:56:47+00:00","dateModified":"2018-10-04T15:12:19+00:00","mainEntityOfPage":{"@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/"},"wordCount":146,"commentCount":0,"publisher":{"@id":"https:\/\/zdvo.org\/de\/#organization"},"image":{"@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#primaryimage"},"thumbnailUrl":"https:\/\/zdvo.org\/wp-content\/uploads\/2018\/04\/513.jpg","articleSection":["About","BEIT HALOCHEM-ZENTREN"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/","url":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/","name":"Ein \"Zweites Zuhause\" \u2013 Beit Halochem-Zentren - zdvo.org","isPartOf":{"@id":"https:\/\/zdvo.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#primaryimage"},"image":{"@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#primaryimage"},"thumbnailUrl":"https:\/\/zdvo.org\/wp-content\/uploads\/2018\/04\/513.jpg","datePublished":"2018-04-10T19:56:47+00:00","dateModified":"2018-10-04T15:12:19+00:00","breadcrumb":{"@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#primaryimage","url":"https:\/\/zdvo.org\/wp-content\/uploads\/2018\/04\/513.jpg","contentUrl":"https:\/\/zdvo.org\/wp-content\/uploads\/2018\/04\/513.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/zdvo.org\/de\/a-second-home-beit-halochem-centers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zdvo.org\/de\/"},{"@type":"ListItem","position":2,"name":"Ein &#8222;Zweites Zuhause&#8220; \u2013 Beit Halochem-Zentren"}]},{"@type":"WebSite","@id":"https:\/\/zdvo.org\/de\/#website","url":"https:\/\/zdvo.org\/de\/","name":"zdvo.org","description":"The Zahal Disabled Veterans Organization (ZDVO) is a registered non-profit organization with the purpose of providing disabled veterans all their needs towards their rehabilitation.","publisher":{"@id":"https:\/\/zdvo.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zdvo.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/zdvo.org\/de\/#organization","name":"zdvo","url":"https:\/\/zdvo.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zdvo.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/zdvo.org\/wp-content\/uploads\/2026\/02\/KEREN_IDF_Veterans_ENGLISH_Beit_ha_lochem_Logo_CMYK_Blue.png","contentUrl":"https:\/\/zdvo.org\/wp-content\/uploads\/2026\/02\/KEREN_IDF_Veterans_ENGLISH_Beit_ha_lochem_Logo_CMYK_Blue.png","width":1566,"height":382,"caption":"zdvo"},"image":{"@id":"https:\/\/zdvo.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zdvo.halochem\/"]},{"@type":"Person","@id":"https:\/\/zdvo.org\/de\/#\/schema\/person\/2ed98dea9ff2fe660f1caf1174f49fcf","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/297c0af693852fda6a0b04cc7e57c482a131fcde794e6c4cc3be61fc94a42b7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/297c0af693852fda6a0b04cc7e57c482a131fcde794e6c4cc3be61fc94a42b7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/297c0af693852fda6a0b04cc7e57c482a131fcde794e6c4cc3be61fc94a42b7c?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/zdvo.org\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/posts\/3722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/comments?post=3722"}],"version-history":[{"count":2,"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/posts\/3722\/revisions"}],"predecessor-version":[{"id":4116,"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/posts\/3722\/revisions\/4116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/media\/3723"}],"wp:attachment":[{"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/media?parent=3722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/categories?post=3722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zdvo.org\/de\/wp-json\/wp\/v2\/tags?post=3722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}